{"id":15527,"date":"2025-01-14T18:14:18","date_gmt":"2025-01-14T17:14:18","guid":{"rendered":"https:\/\/www.old-design.com\/produit\/biblioteca-poul-cadovius-cado-system\/"},"modified":"2026-05-19T12:10:35","modified_gmt":"2026-05-19T10:10:35","slug":"biblioteca-poul-cadovius-cado-system","status":"publish","type":"product","link":"https:\/\/www.old-design.com\/es\/produit\/biblioteca-poul-cadovius-cado-system\/","title":{"rendered":"Biblioteca Poul Cadovius Cado System"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3131-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"3131\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/product\/15527#wpcf7-f3131-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3131\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3131-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Nom<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> E-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-197\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email-197\" \/><\/span> <\/label>\n<\/p>\n<p><label> T\u00e9l\u00e9phone<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-708\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-708\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<h2>Biblioteca modular danesa de los a\u00f1os 60 en palisandro de R\u00edo dise\u00f1ada por Poul Cadovius para el editor Cado.<\/h2>\n<p>Conserva el sello original \u201cMade in Denmark\u201d en la parte trasera de los m\u00f3dulos y estanter\u00edas.<\/p>\n<p>Las baldas y m\u00f3dulos se insertan f\u00e1cilmente en los montantes mediante el sistema de fijaci\u00f3n Cado, sin necesidad de herramientas.<\/p>\n<p>Las escuadras en forma de boomerang presentan una calidad de fabricaci\u00f3n ejemplar.<\/p>\n<p>El conjunto permite m\u00faltiples configuraciones gracias a su sistema totalmente modular.<\/p>\n<p>Se trata de la versi\u00f3n m\u00e1s lujosa del cat\u00e1logo de 1969, realizada en palisandro de R\u00edo.<\/p>\n<p>El conjunto se encuentra en muy buen estado vintage.<\/p>\n<p>&nbsp;<\/p>\n<p>Dimensiones :<\/p>\n<p>&#8211; 6 estanter\u00edas An. 80 cm \u00d7 Prof. 22 cm<\/p>\n<p>&#8211; 1 m\u00f3dulo con puertas correderas<br \/>Incluye una balda interior regulable en altura y un elegante caj\u00f3n interior con tirador integrado y fieltro verde.<\/p>\n<p>Alt. 51,5 cm \u00d7 An. 80 cm \u00d7 Prof. 46 cm<\/p>\n<p>&#8211; 1 m\u00f3dulo c\u00f3moda con 4 cajones<\/p>\n<p>Alt. 51,5 cm \u00d7 An. 80 cm \u00d7 Prof. 46 cm<\/p>\n<p>&#8211; 1 m\u00f3dulo vitrina superior (Cristales desmontables y dos estanter\u00edas de vidrio extra\u00edbles.) An. 80 cm \u00d7 Alt. 56 cm \u00d7 Prof. 24 cm<\/p>\n<p>Largo total: 244 cm<br \/>\nAltura en fotograf\u00edas: 205 cm<br \/>\nAltura de los montantes: 202 cm<\/p>\n<p>Old-Design realiza entregas en toda Francia y Europa.<\/p>\n<p>Worldwide Shipping<\/p>\n","protected":false},"featured_media":15596,"template":"","meta":{"_seopress_titles_title":"Biblioteca Poul Cadovius, a\u00f1os 60","_seopress_titles_desc":"Biblioteca danesa de los a\u00f1os 60 dise\u00f1ada por Poul Cadovius en palisandro de R\u00edo.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_vp_format_video_url":"","_vp_image_focal_point":[]},"product_brand":[],"product_cat":[583,592],"product_tag":[],"class_list":["post-15527","product","type-product","status-publish","has-post-thumbnail","product_cat-almacenamiento","product_cat-bibliotecas","first","outofstock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/product\/15527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/product\/15527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/media\/15596"}],"wp:attachment":[{"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/media?parent=15527"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/product_brand?post=15527"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/product_cat?post=15527"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.old-design.com\/es\/wp-json\/wp\/v2\/product_tag?post=15527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}